{"id":3361,"date":"2024-05-03T11:33:32","date_gmt":"2024-05-03T09:33:32","guid":{"rendered":"https:\/\/www.titanium.aero\/?p=3361"},"modified":"2024-05-03T11:33:32","modified_gmt":"2024-05-03T09:33:32","slug":"occurrence-reporting-2","status":"publish","type":"post","link":"https:\/\/www.titanium.aero\/sms-2\/occurence_reporting\/","title":{"rendered":"OCCURRENCE REPORTING"},"content":{"rendered":"<p>Dieses Modul dient der Erfassung und \u00dcberwachung aller gemeldeten Ereignisse.<br \/>\nZu den grundlegenden Funktionen geh\u00f6ren:<br \/>\nDie Eingabe von Ereignissen kann anonymisiert werden, um die Vertraulichkeit der meldenden Person zu wahren, die M\u00f6glichkeit, Bilder des jeweiligen gemeldeten Ereignisses hochzuladen und zu speichern, die Aufzeichnung der Details von Luftfahrzeugen und Komponenten, bei denen das Ereignis aufgetreten ist, die Eingabe mehrerer Ma\u00dfnahmen zur Behebung der gemeldeten Ereignisse mit der Option, eine Verkn\u00fcpfung zu einem bereits im System angelegten Defekt herzustellen, die Verwaltung externer Dokumente und die Einrichtung von E-Mail-Vorlagen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dieses Modul dient der Erfassung und \u00dcberwachung aller gemeldeten Ereignisse.  [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":3354,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[39,119],"tags":[],"class_list":["post-3361","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-german-posts","category-sms-modules"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.titanium.aero\/index.php\/wp-json\/wp\/v2\/posts\/3361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.titanium.aero\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.titanium.aero\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.titanium.aero\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.titanium.aero\/index.php\/wp-json\/wp\/v2\/comments?post=3361"}],"version-history":[{"count":0,"href":"https:\/\/www.titanium.aero\/index.php\/wp-json\/wp\/v2\/posts\/3361\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.titanium.aero\/index.php\/wp-json\/wp\/v2\/media\/3354"}],"wp:attachment":[{"href":"https:\/\/www.titanium.aero\/index.php\/wp-json\/wp\/v2\/media?parent=3361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.titanium.aero\/index.php\/wp-json\/wp\/v2\/categories?post=3361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.titanium.aero\/index.php\/wp-json\/wp\/v2\/tags?post=3361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}