{"id":1942,"date":"2022-12-16T14:04:56","date_gmt":"2022-12-16T13:04:56","guid":{"rendered":"https:\/\/www.titanium.aero\/?p=1942"},"modified":"2022-12-16T14:04:56","modified_gmt":"2022-12-16T13:04:56","slug":"schichtplaene-und-kapazitaeten","status":"publish","type":"post","link":"https:\/\/www.titanium.aero\/index.php\/2022\/12\/16\/schichtplaene-und-kapazitaeten\/","title":{"rendered":"SCHICHTPL\u00c4NE UND KAPAZIT\u00c4TEN"},"content":{"rendered":"<p>Sie k\u00f6nnen im System beliebige Schichten erstellen und verwalten, inklusive Ber\u00fccksichtigung von unterschiedlichen Pause-Zeiten sowie abweichenden Feiertagsschemata je Bundesland. Die Schichten k\u00f6nnen Mitarbeitern und Maschinen zugewiesen werden und anhand eines rollierenden Wochenplans erstellt werden. Pro Ressource kann ebenfalls ein prozentualer Nutzungsgrad hinterlegt und somit eine finite Kapazit\u00e4tsplanung durchgef\u00fchrt werden. Alternativ kann diese Berechnung auch durch infinite oder engpassbestimmte Kapazit\u00e4ten erfolgen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sie k\u00f6nnen im System beliebige Schichten erstellen und verwalten, inklusive  [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[39,59],"tags":[],"class_list":["post-1942","post","type-post","status-publish","format-standard","hentry","category-german-posts","category-personal-module"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.titanium.aero\/index.php\/wp-json\/wp\/v2\/posts\/1942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.titanium.aero\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.titanium.aero\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.titanium.aero\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.titanium.aero\/index.php\/wp-json\/wp\/v2\/comments?post=1942"}],"version-history":[{"count":0,"href":"https:\/\/www.titanium.aero\/index.php\/wp-json\/wp\/v2\/posts\/1942\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.titanium.aero\/index.php\/wp-json\/wp\/v2\/media?parent=1942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.titanium.aero\/index.php\/wp-json\/wp\/v2\/categories?post=1942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.titanium.aero\/index.php\/wp-json\/wp\/v2\/tags?post=1942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}